{"id":1197,"date":"2022-07-11T12:14:28","date_gmt":"2022-07-11T10:14:28","guid":{"rendered":"https:\/\/museen-lemgo.de\/frenkelhaus\/gedenkwoche-karla-raveh-copy-copy\/"},"modified":"2022-07-21T09:02:00","modified_gmt":"2022-07-21T07:02:00","slug":"gedenkwoche-rosalie-abraham","status":"publish","type":"page","link":"https:\/\/museen-lemgo.de\/frenkelhaus\/gedenkwoche-rosalie-abraham\/","title":{"rendered":"Gedenkwoche Rosalie Abraham"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1197","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 06:47:55","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"language","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/pages\/1197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/comments?post=1197"}],"version-history":[{"count":6,"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/pages\/1197\/revisions"}],"predecessor-version":[{"id":1384,"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/pages\/1197\/revisions\/1384"}],"wp:attachment":[{"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/media?parent=1197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}