{"id":1244,"date":"2022-07-11T14:47:51","date_gmt":"2022-07-11T12:47:51","guid":{"rendered":"https:\/\/museen-lemgo.de\/frenkelhaus\/gedenkwoche_ehepaar-katzenstein-copy\/"},"modified":"2022-07-20T13:01:42","modified_gmt":"2022-07-20T11:01:42","slug":"gedenkwoche_familie-juchenheim","status":"publish","type":"page","link":"https:\/\/museen-lemgo.de\/frenkelhaus\/gedenkwoche_familie-juchenheim\/","title":{"rendered":"Gedenkwoche Familie Juchenheim"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1244","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 06:47:55","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"language","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/pages\/1244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/comments?post=1244"}],"version-history":[{"count":4,"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/pages\/1244\/revisions"}],"predecessor-version":[{"id":1342,"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/pages\/1244\/revisions\/1342"}],"wp:attachment":[{"href":"https:\/\/museen-lemgo.de\/frenkelhaus\/wp-json\/wp\/v2\/media?parent=1244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}